{"id":8286,"date":"2012-11-13T13:50:02","date_gmt":"2012-11-13T12:50:02","guid":{"rendered":"http:\/\/tradingjobs.bontrade.org\/?p=8286"},"modified":"2012-11-13T13:50:02","modified_gmt":"2012-11-13T12:50:02","slug":"junior-jet-fuel-trader-energy-recruiters-eri-united-states","status":"publish","type":"post","link":"https:\/\/bontrade.org\/blog49\/8286\/junior-jet-fuel-trader-energy-recruiters-eri-united-states\/","title":{"rendered":"Junior Jet Fuel Trader - Energy Recruiters (ERI) - United States"},"content":{"rendered":"<p>Our Client, a premier global fuel distribution company is seeking a Jet Fuel Trader based in Southwestern US. Reporting the operating budget for specified field...  $60,000 - $70,000 a year<br \/>\n            From Energy Recruiters (ERI) - 13 Nov 2012 12:36:07 GMT<br \/>\n            -  View all <a href=\"http:\/\/www.indeed.com\/l-United-States-jobs.html\"> jobs<\/a><\/p>\n<p>View full post on <a href=\"http:\/\/www.indeed.com\/job\/Junior-Jet-Fuel-Trader-at-Energy-Recruiters-in-United-States-acb3a40e6c543eeb\">Trader Jobs | Indeed.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Our Client, a premier global fuel distribution company is seeking a Jet Fuel Trader based in Southwestern US. Reporting the operating budget for specified field... $60,000 - $70,000 a year From Energy Recruiters (ERI) - 13 Nov 2012 12:36:07 GMT - View all jobs View full post on Trader Jobs | Indeed.com<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lightning_design_setting":[],"footnotes":""},"categories":[4520],"tags":[1826,5269,4596,5964,2603,1460,2413],"class_list":["post-8286","post","type-post","status-publish","format-standard","hentry","category-tradingjobsearch","tag-energy","tag-fuel","tag-junior","tag-recruiters","tag-states","tag-trader","tag-united"],"_links":{"self":[{"href":"https:\/\/bontrade.org\/blog49\/wp-json\/wp\/v2\/posts\/8286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bontrade.org\/blog49\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bontrade.org\/blog49\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bontrade.org\/blog49\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bontrade.org\/blog49\/wp-json\/wp\/v2\/comments?post=8286"}],"version-history":[{"count":0,"href":"https:\/\/bontrade.org\/blog49\/wp-json\/wp\/v2\/posts\/8286\/revisions"}],"wp:attachment":[{"href":"https:\/\/bontrade.org\/blog49\/wp-json\/wp\/v2\/media?parent=8286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bontrade.org\/blog49\/wp-json\/wp\/v2\/categories?post=8286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bontrade.org\/blog49\/wp-json\/wp\/v2\/tags?post=8286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}